{"id":4339,"date":"2021-02-18T15:44:34","date_gmt":"2021-02-18T14:44:34","guid":{"rendered":"http:\/\/blogs.unsw.edu.au\/nowideas\/?p=4339"},"modified":"2025-02-27T20:03:12","modified_gmt":"2025-02-27T19:03:12","slug":"ecommerce-fortalecen-ventas-confinamiento","status":"publish","type":"post","link":"https:\/\/blogs.unsw.edu.au\/nowideas\/blog\/2021\/02\/ecommerce-fortalecen-ventas-confinamiento\/","title":{"rendered":"Los eCommerce fortalecen sus ventas por restricciones del confinamiento"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p>El miedo a contraer la Covid-19 y las restricciones que implica el confinamiento, han fortalecido el <strong>eCommerce<\/strong> en el \u00faltimo a\u00f1o. Esto es debido a que la gente ha cambiado la forma en que adquieren los productos y servicios, debido a que pasamos de comprar de forma presencial, para hacerlo a trav\u00e9s de internet.<\/p>\n\n\n\n<p>En este sentido, estudios sobre la econom\u00eda y el comportamiento de las personas durante la cuarentena, han revelado que Espa\u00f1a es la naci\u00f3n europea que m\u00e1s ha incrementado las <strong>ventas online,<\/strong> esto se traduce en un 67%.&nbsp; Los espa\u00f1oles son seguidos de cerca por los italianos e un 66%, y los portugueses con un 62% de incremento del comercio electr\u00f3nico.<\/p>\n\n\n\n<p>Es decir, que aquellos reacios a utilizar <strong>pagos por internet<\/strong> ahora vieron la comodidad que esta metodolog\u00eda ofrece. Es por ello que mientras el turismo o las aerol\u00edneas se han visto debilitados, los siguientes sectores de la econom\u00eda han logrado un repunte impresionante:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. Sector de la moda<\/h2>\n\n\n\n<p>La venta de ropa y otros art\u00edculos de la moda han sido uno de los m\u00e1s beneficiados. Dato que se confirma con los 806 millones de euros que se gener\u00f3 entre enero y marzo del 2020, una cifra superior respecto a la cantidad de 651 millones producidos durante el mismo periodo del 2019.<\/p>\n\n\n\n<p>La <strong>compra de prendas de vestir<\/strong>, sobre todo en el caso de las personas de alto riesgo o mujeres en estado de gestaci\u00f3n han aumentado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Sector reformas<\/h2>\n\n\n\n<p>Un informe realizado por ciertas empresas dedicadas a las ventas de art\u00edculos especializados para hacer reformas, indic\u00f3 que el 61% de los espa\u00f1oles ten\u00edan la disposici\u00f3n de hacer reformas en sus casas durante el confinamiento. Es por ello que el <strong>comercio electr\u00f3nico<\/strong> dedicado a la venta de productos para el embellecimiento y cuidado del hogar ha visto un gran incremento en sus ingresos.<\/p>\n\n\n\n<p>En este aspecto, las categor\u00edas con m\u00e1s demanda durante el confinamiento han sido las de decoraci\u00f3n, mobiliario y entretenimiento. Tal es el caso de las ventas de piscinas, juegos o accesorios de cocina, como la <a href=\"https:\/\/mueblesgavira.es\/mesa-comedor-urban\" target=\"_blank\" rel=\"noreferrer noopener\">mesa comedor grande<\/a>, cuya estructura de acero es extensible y permite el desplazamiento de las patas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Alimentaci\u00f3n<\/h2>\n\n\n\n<p>Durante el confinamiento, la venta de productos de primera necesidad a trav\u00e9s de internet se triplic\u00f3, como es el caso de los alimentos. En este sentido, los productos frescos han sido los que m\u00e1s demanda implican, tal es el caso de la carne, frutas y verduras.<\/p>\n\n\n\n<p>Sin embargo, el <strong>eCommerce de comidas preparadas <\/strong>es uno de los que m\u00e1s ventas ha generado, que se refleja en el aumento del 300% respecto a los a\u00f1os anteriores. El auge de este sector econ\u00f3mico se debe al tambi\u00e9n incremento de la modalidad de teletrabajo, como consecuencia del confinamiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Electr\u00f3nica<\/h2>\n\n\n\n<p>Producto del teletrabajo muchos espa\u00f1oles han tenido que modernizar y adaptar sus hogares a esta modalidad, que implica la <strong>compra de productos electr\u00f3nicos<\/strong>. Es por ello que la demanda de computadoras port\u00e1tiles, impresoras, monitores y de otros dispositivos de este tipo han producido buenos ingresos a los comerciantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5. Belleza<\/h2>\n\n\n\n<p>Este sector prev\u00e9 que los nuevos h\u00e1bitos de <strong>compra online<\/strong> se mantendr\u00e1n, mismos que fueron adquiridos a ra\u00edz de las restricciones de seguridad, debido a la pandemia generada por la Covid-19. Las <a href=\"https:\/\/naturaonline.es\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tiendas de cosm\u00e9tica natural<\/strong><\/a>, han incrementado su venta online m\u00e1s de un 200% en el \u00faltimo a\u00f1o.<\/p>\n\n\n\n<p>En relaci\u00f3n a ello, el<strong> eCommerce ha permitido la estabilidad de empresas<\/strong> dedicadas a la producci\u00f3n de art\u00edculos. Algo que se refleja con el aumento de las ventas para los productos relacionados con la cosm\u00e9tica y belleza que durante el 2020 fue del 16,5% respecto al a\u00f1o anterior.<\/p>\n\n\n\n<p><span style=\"color: #808080; font-size: 14px;\">Imagen: Freepik<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El miedo a contraer la Covid-19 y las restricciones que implica el confinamiento, han fortalecido el eCommerce en el \u00faltimo a\u00f1o. Descubre los sectores m\u00e1s beneficiados&#8230;<\/p>\n","protected":false},"author":72389,"featured_media":4340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[47680],"tags":[47692],"class_list":["post-4339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agencias"],"_links":{"self":[{"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/posts\/4339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/users\/72389"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/comments?post=4339"}],"version-history":[{"count":2,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/posts\/4339\/revisions"}],"predecessor-version":[{"id":4347,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/posts\/4339\/revisions\/4347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/media\/4340"}],"wp:attachment":[{"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/media?parent=4339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/categories?post=4339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.unsw.edu.au\/nowideas\/wp-json\/wp\/v2\/tags?post=4339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}